{"id":36110,"date":"2026-02-26T18:29:52","date_gmt":"2026-02-26T18:29:52","guid":{"rendered":"https:\/\/www.rbcroyalbank.com\/fr-ca\/?post_type=rbc_my_money_matter&#038;p=36110"},"modified":"2026-02-26T18:30:56","modified_gmt":"2026-02-26T18:30:56","slug":"protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin","status":"publish","type":"rbc_my_money_matter","link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","title":{"rendered":"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin"},"content":{"rendered":"\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<p>Les organisations canadiennes re\u00e7oivent depuis un certain temps de nombreux messages qui semblent provenir de sources de confiance, mais qui \u00e9manent en fait de fraudeurs.<\/p>\n\n\n\n<p>L\u2019ann\u00e9e derni\u00e8re, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes. Selon une <a href=\"https:\/\/www.paiements.ca\/perspectives\/recherche\/une-entreprise-canadienne-sur-cinq-ete-victime-dune-fraude-de-paiement-au\" data-dig-id=\"LP-36110-fd50a4ce\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"\u00e9tude\" class=\"rbc-link-format\">\u00e9tude<\/a> r\u00e9alis\u00e9e par Paiements Canada en 2024, une&nbsp;entreprise sur cinq a \u00e9t\u00e9 victime d\u2019une fraude li\u00e9e aux paiements au cours des six&nbsp;mois pr\u00e9c\u00e9dents, ce qui a entra\u00een\u00e9 des pertes financi\u00e8res dans un&nbsp;cas sur sept.<\/p>\n\n\n\n<p>En fait, la proportion d\u2019organisations ayant \u00e9t\u00e9 vis\u00e9es par une fraude a \u00e9t\u00e9 plus \u00e9lev\u00e9e que chez les consommateurs canadiens, alors m\u00eame qu\u2019une majorit\u00e9 avait la certitude d\u2019\u00eatre bien prot\u00e9g\u00e9e. Le type de fraude le plus couramment utilis\u00e9 contre les entreprises du Canada pendant cette p\u00e9riode est la fraude par usurpation d\u2019identit\u00e9, qui a repr\u00e9sent\u00e9 le quart de tous les signalements d\u2019escroqueries li\u00e9es aux paiements.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"257\" width=\"1024\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/1-in-4-impersonator-fraud-FR.jpg?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-37816\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/1-in-4-impersonator-fraud-FR.jpg 1440w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/1-in-4-impersonator-fraud-FR.jpg?resize=300,75 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/1-in-4-impersonator-fraud-FR.jpg?resize=768,193 768w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/1-in-4-impersonator-fraud-FR.jpg?resize=1024,257 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-en-quoi-consiste-une-fraude-par-usurpation-d-identite\">En quoi consiste une fraude par usurpation d\u2019identit\u00e9 ?<\/h2>\n\n\n\n<p>Le succ\u00e8s de ce stratag\u00e8me repose sur le fait que le fraudeur se fait passer pour une source de confiance afin d\u2019\u00e9viter de subir un examen minutieux et de se faire d\u00e9tecter. Il communique par courriel, par texto, par message sur les m\u00e9dias sociaux et m\u00eame par t\u00e9l\u00e9phone pour demander un paiement ou des renseignements confidentiels en pr\u00e9tendant travailler pour une entreprise, une institution ou une organisation de confiance.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.canada.ca\/fr\/bureau-concurrence\/nouvelles\/2025\/02\/le-mois-de-la-prevention-de-la-fraude-met-laccent-sur-la-fraude-par-usurpation-didentite-lune-des-formes-de-fraude-qui-connait-la-croissance-la-plu.html\" data-dig-id=\"LP-36110-00105c69\" data-dig-label=\"Selon le Centre antifraude du Canada, le Bureau de la concurrence et la Gendarmerie royale du Canada (GRC)\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">Selon le Centre antifraude du Canada, le Bureau de la concurrence et la Gendarmerie royale du Canada (GRC)<\/a>, l\u2019usurpation d\u2019identit\u00e9 est l\u2019une des formes de fraude affichant la croissance la plus rapide au pays. En 2024, le Centre antifraude du Canada a re\u00e7u plus de 108\u00a0000\u00a0signalements provenant de plus de 34\u00a0600\u00a0victimes, dont les pertes financi\u00e8res imputables aux fraudes en ligne s\u2019\u00e9l\u00e8vent \u00e0 638\u00a0milliards de dollars. Ce sont plus de 2\u00a0milliards de dollars que les Canadiens ont perdus aux mains des fraudeurs en ligne depuis 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fonctionnement-d-une-fraude-par-usurpation-d-identite\">Fonctionnement d\u2019une fraude par usurpation d\u2019identit\u00e9<\/h2>\n\n\n\n<p>La fraude par usurpation d\u2019identit\u00e9 peut \u00eatre d\u2019une grande efficacit\u00e9 et faire des ravages sur le plan financier, puisqu\u2019elle exploite des relations existantes avec des sources de confiance, y compris des fournisseurs, des institutions financi\u00e8res, des services de messagerie, des employ\u00e9s, des clients, des autorit\u00e9s polici\u00e8res et des organismes de r\u00e9glementation.<\/p>\n\n\n\n<p>Pour mener \u00e0 bien son stratag\u00e8me, le fraudeur doit parfois conna\u00eetre les contacts professionnels avec qui sa victime a l\u2019habitude de faire affaire. Cependant, il pr\u00e9tend g\u00e9n\u00e9ralement entrer en contact avec la personne au nom d\u2019une institution, d\u2019une organisation ou d\u2019une entreprise de services couramment utilis\u00e9e.<\/p>\n\n\n\n<p>Souvent, l\u2019escroc laisse entendre qu\u2019une op\u00e9ration non autoris\u00e9e a eu lieu, qu\u2019une commande n\u2019a pas \u00e9t\u00e9 re\u00e7ue, que des sommes ou des taxes exigibles sont en souffrance ou qu\u2019un paiement a \u00e9t\u00e9 envoy\u00e9 vers le mauvais compte. Dans la quasi-totalit\u00e9 des cas, le fraudeur tente d\u2019obtenir des renseignements confidentiels, comme des mots de passe, un num\u00e9ro d\u2019assurance sociale ou des informations bancaires, ou demande \u00e0 la victime d\u2019effectuer un paiement.<\/p>\n\n\n\n<p>Pour rendre leurs demandes plus cr\u00e9dibles, les escrocs font \u00e9galement appel \u00e0 l\u2019intelligence artificielle, \u00e0 des donn\u00e9es recueillies lors d\u2019une violation ou d\u2019un piratage ant\u00e9rieur, ou \u00e0 des renseignements publics. Il arrive aussi qu\u2019ils dirigent la victime vers un site Web \u00ab\u00a0clon\u00e9\u00a0\u00bb qui semble identique au site l\u00e9gitime de l\u2019organisation, ou qu\u2019ils clonent des num\u00e9ros de t\u00e9l\u00e9phone et des renseignements relatifs \u00e0 l\u2019identification de l\u2019appelant afin de para\u00eetre authentiques.<\/p>\n\n\n\n<p><strong>Pour en savoir plus\u00a0: <\/strong><a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-et-de-vos-employes-contre-la-fraude-de-mot-de-passe\/\" data-dig-id=\"LP-36110-9edd421b\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"Protection de votre entreprise et de vos employ\u00e9s contre la fraude de mot de passe\" class=\"rbc-link-format\">Protection de votre entreprise et de vos employ\u00e9s contre la fraude de mot de passe<\/a><\/p>\n\n\n\n<p>Les entreprises sont souvent la cible de deux&nbsp;types de fraude par usurpation d\u2019identit\u00e9&nbsp;: les courriels d\u2019affaires et de fournisseurs compromis.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-compromission-de-messagerie-d-entreprise\">Compromission de messagerie d\u2019entreprise<\/h3>\n\n\n\n<p>La compromission de messagerie d\u2019entreprise est une <a href=\"https:\/\/www.microsoft.com\/fr-ca\/security\/business\/security-101\/what-is-business-email-compromise-bec\" data-dig-id=\"LP-36110-24b21c81\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"escroquerie sophistiqu\u00e9e\" class=\"rbc-link-format\">escroquerie sophistiqu\u00e9e<\/a> qui cherche \u00e0 profiter de relations d\u2019affaires existantes de confiance. Ces courriels sont tr\u00e8s cibl\u00e9s et difficiles \u00e0 rep\u00e9rer. Ils visent \u00e0 se faire passer pour des dirigeants de confiance, comme le chef de la direction, pour inciter des employ\u00e9s \u00e0 partager des donn\u00e9es sensibles ou \u00e0 les pousser \u00e0 transf\u00e9rer des fonds. En plus de l\u2019escroquerie au chef de la direction, la compromission de messagerie d\u2019entreprise peut \u00e9galement survenir par une compromission de compte, c\u2019est-\u00e0-dire par le vol de mots de passe ou par l\u2019usurpation de l\u2019identit\u00e9 d\u2019un avocat, consistant pour les fraudeurs \u00e0 falsifier des documents juridiques pour faire pression sur les employ\u00e9s afin qu\u2019ils effectuent des paiements.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-compromission-du-courriel-d-un-fournisseur\">Compromission du courriel d\u2019un fournisseur<\/h3>\n\n\n\n<p>Semblable aux escroqueries par compromission de messagerie d\u2019entreprise, l\u2019escroquerie par compromission du courriel de fournisseur consiste pour un cybercriminel \u00e0 usurper l\u2019identit\u00e9 d\u2019un fournisseur ou \u00e0 prendre le contr\u00f4le de son compte de courriel. En se faisant passer pour un fournisseur de confiance, les cybercriminels peuvent \u00e9mettre des factures ou des documents de facturation pour d\u00e9tourner les paiements vers leurs propres comptes bancaires.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"257\" width=\"1024\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/45-of-business-email-fraud-FR.jpg?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-37820\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/45-of-business-email-fraud-FR.jpg 1440w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/45-of-business-email-fraud-FR.jpg?resize=300,75 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/45-of-business-email-fraud-FR.jpg?resize=768,193 768w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/45-of-business-email-fraud-FR.jpg?resize=1024,257 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-indices-a-surveiller-pour-reperer-une-usurpation-d-identite\">Indices \u00e0 surveiller pour rep\u00e9rer une usurpation d\u2019identit\u00e9<\/h2>\n\n\n\n<p>La meilleure fa\u00e7on de se prot\u00e9ger contre la fraude par usurpation d\u2019identit\u00e9 est d\u2019\u00eatre conscient de son existence, de faire preuve de prudence et de demeurer sur ses gardes devant certains signes r\u00e9v\u00e9lateurs.<\/p>\n\n\n\n<p>Par exemple, un grand nombre de demandes frauduleuses misent sur le fait que les utilisateurs agiront avant de r\u00e9fl\u00e9chir, ce qui explique que les demandes de fonds ou de renseignements semblent souvent urgentes. Le caract\u00e8re urgent des communications fait donc partie des signes \u00e0 surveiller.<\/p>\n\n\n\n<p>De plus, il faut faire preuve d\u2019une grande prudence face aux demandes de renseignements personnels ou confidentiels qui ont d\u00e9j\u00e0 \u00e9t\u00e9 fournis ou qui semblent inutiles vu la nature de votre relation avec l\u2019organisation ou la personne \u00e0 l\u2019origine de la demande.<\/p>\n\n\n\n<p>Enfin, les demandes de paiement ou d\u2019envoi de fonds qui sortent du cadre existant de l\u2019organisation, par exemple les versements vers un nouveau compte ou au moyen d\u2019un nouveau portail de paiement, exigent une enqu\u00eate plus pouss\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-escroqueries-par-usurpation-d-identite-bancaire\">Escroqueries par usurpation d\u2019identit\u00e9 bancaire<\/h3>\n\n\n\n<p>Une escroquerie par usurpation d\u2019identit\u00e9 bancaire peut commencer par un texto, un appel t\u00e9l\u00e9phonique ou un courriel qui semble provenir d\u2019une institution financi\u00e8re affirmant qu\u2019il y a un probl\u00e8me urgent avec un compte, comme une atteinte \u00e0 la s\u00e9curit\u00e9 ou une transition non autoris\u00e9e, ou la recherche de donn\u00e9es sensibles. Nous ne demanderons jamais \u00e0 un client de RBC de fournir des renseignements bancaires confidentiels comme des mots de passe, des codes d\u2019acc\u00e8s \u00e0 usage unique ou des jetons.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-decelez-les-indices\">D\u00e9celez les indices<\/h3>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-blue-disc mar-l mob-mar-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Pr\u00eatez attention \u00e0 l\u2019adresse courriel ou \u00e0 l\u2019identifiant de l\u2019exp\u00e9diteur<\/strong>. Les fraudeurs peuvent falsifier les coordonn\u00e9es pour para\u00eetre l\u00e9gitimes. Les adresses courriel peuvent \u00eatre pirat\u00e9es ou falsifi\u00e9es en cr\u00e9ant des adresses qui semblent l\u00e9gitimes \u00e0 premi\u00e8re vue.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Faites attention aux fausses urgences ou importances<\/strong>, car les criminels cherchent \u00e0 faire pression sur les destinataires pour qu\u2019ils r\u00e9agissent imm\u00e9diatement.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Faites bien attention aux pi\u00e8ces jointes et aux hyperliens<\/strong> <strong>avant de cliquer<\/strong>. Une s\u00e9rie de lettres et de chiffres al\u00e9atoires pourrait indiquer qu\u2019il s\u2019agit d\u2019un hame\u00e7on.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Soyez attentifs aux demandes de t\u00e9l\u00e9charger un logiciel sur votre syst\u00e8me<\/strong>. Si vous avez des doutes au sujet d\u2019une demande, mettez fin \u00e0 la conversation et appelez le fournisseur ou le partenaire au num\u00e9ro figurant dans vos dossiers.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Soyez \u00e0 l\u2019aff\u00fbt des pirates informatiques qui utilisent le caract\u00e8re saisonnier de certaines op\u00e9rations pour para\u00eetre plus l\u00e9gitimes<\/strong>, comme la p\u00e9riode des imp\u00f4ts.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-prevention-des-fraudes-par-usurpation-d-identite\">Pr\u00e9vention des fraudes par usurpation d\u2019identit\u00e9<\/h2>\n\n\n\n<p>Si vous recevez une demande urgente de renseignements personnels ou de paiement, en particulier si les fonds ou les informations doivent \u00eatre envoy\u00e9s vers une nouvelle adresse, un nouveau compte ou un nouveau site Web, il est important de mener une enqu\u00eate plus approfondie avant de faire quoi que ce soit. Cette \u00e9tape doit \u00eatre suivie m\u00eame si le message semble provenir d\u2019une source de confiance.<\/p>\n\n\n\n<p>Bien que ce type de fraude vise souvent \u00e0 imiter des sources et des contacts l\u00e9gitimes, il existe souvent des signes subtils que l\u2019exp\u00e9diteur n\u2019est pas qui il pr\u00e9tend \u00eatre. Il peut par exemple s\u2019agir de diff\u00e9rences mineures dans l\u2019adresse courriel, d\u2019erreurs d\u2019orthographe ou d\u2019un appel provenant d\u2019un num\u00e9ro inconnu.<\/p>\n\n\n\n<p>Si vous n\u2019\u00eates pas certain de la l\u00e9gitimit\u00e9 d\u2019un exp\u00e9diteur, essayez de communiquer avec lui au moyen de ses coordonn\u00e9es officielles ou de celles que vous avez utilis\u00e9es par le pass\u00e9. Ainsi, si vous recevez par exemple un courriel d\u2019un soi-disant fournisseur exigeant un paiement suppl\u00e9mentaire pour une commande r\u00e9cente, appelez directement son bureau plut\u00f4t que de r\u00e9pondre au courriel.<\/p>\n\n\n\n<p>Nous invitons les entreprises \u00e0 int\u00e9grer \u00e0 leurs politiques l\u2019obligation de demander, lors de chaque op\u00e9ration, des renseignements que seule la source l\u00e9gitime peut conna\u00eetre, par exemple, les d\u00e9tails d\u2019une commande pr\u00e9c\u00e9dente, des num\u00e9ros de facture ou des identifiants de clients.<\/p>\n\n\n\n<p>Les organisations de toutes les tailles peuvent \u00e9galement mieux se prot\u00e9ger en adoptant de robustes outils de pr\u00e9vention et de d\u00e9tection de la fraude, comme <a href=\"https:\/\/kobalt.io\/\" data-dig-id=\"LP-36110-e6272356\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"Kobalt.io\" class=\"rbc-link-format\">Kobalt.io<\/a> (ce lien m\u00e8ne \u00e0 un site web dont le contenu est en anglais seulement), un partenaire Au-del\u00e0 des services bancaires RBC.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-protegez-votre-entreprise\">Prot\u00e9gez votre entreprise<\/h3>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-blue-disc mar-l mob-mar-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Sensibilisez vos employ\u00e9s \u00e0 ces types d\u2019escroquerie <\/strong>et demandez-leur de se m\u00e9fier des demandes urgentes ou suspectes.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>V\u00e9rifiez la l\u00e9gitimit\u00e9 des demandes de virement de fonds, des factures et des modifications apport\u00e9es aux renseignements bancaires avant de virer des fonds.<\/strong> Ne vous fiez pas uniquement au courriel pour coordonner un virement de fonds \u2013 communiquez en personne ou par t\u00e9l\u00e9phone avant de fournir des renseignements confidentiels ou d\u2019envoyer de l\u2019argent<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Faites attention \u00e0 ce que vous partagez en ligne. <\/strong>Les criminels peuvent utiliser les m\u00e9dias sociaux et votre site Web pour recueillir des renseignements qui serviront \u00e0 usurper votre identit\u00e9.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Le rapprochement des comptes bancaires doit \u00eatre effectu\u00e9 chaque jour <\/strong>afin de rep\u00e9rer toute op\u00e9ration non autoris\u00e9e. Si vous d\u00e9couvrez des op\u00e9rations frauduleuses, vous devez le signaler imm\u00e9diatement \u00e0 votre institution financi\u00e8re.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quoi-faire-en-cas-de-fraude-par-usurpation-d-identite\">Quoi faire en cas de fraude par usurpation d\u2019identit\u00e9<\/h2>\n\n\n\n<p>Nous encourageons les entreprises et les particuliers qui sont victimes d\u2019une fraude par usurpation d\u2019identit\u00e9 \u00e0 signaler imm\u00e9diatement l\u2019incident au&nbsp;<a href=\"https:\/\/antifraudcentre-centreantifraude.ca\/report-signalez-fra.htm\" data-dig-id=\"LP-36110-d877e6cf\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"Centre antifraude du Canada\" class=\"rbc-link-format\">Centre antifraude du Canada<\/a>&nbsp;et \u00e0 mettre fin \u00e0 toute communication avec les fraudeurs pr\u00e9sum\u00e9s.<\/p>\n\n\n\n<p>Par la suite, les organisations devraient rapidement modifier tous leurs mots de passe et identifiants de connexion, m\u00eame ceux associ\u00e9s \u00e0 des comptes non touch\u00e9s, et encourager tous les membres de leur \u00e9quipe \u00e0 faire de m\u00eame. Il peut \u00eatre utile de faire appel \u00e0 un gestionnaire de mots de passe comme <a href=\"https:\/\/1password.com\/fr\" data-dig-id=\"LP-36110-7489b4aa\" data-dig-label=\"1Password\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">1Password<\/a>, partenaire Au-del\u00e0 des services bancaires RBC, pour g\u00e9n\u00e9rer rapidement des mots de passe complexes, uniques et s\u00fbrs pour tous les comptes tout en les rendant accessibles dans une seule application s\u00e9curis\u00e9e.<\/p>\n\n\n\n<p>Si une organisation pense avoir \u00e9t\u00e9 victime d\u2019une fraude par usurpation d\u2019identit\u00e9, elle doit \u00e9galement en aviser son institution financi\u00e8re en vue de suspendre les paiements et de s\u00e9curiser les comptes. Selon une \u00e9tude de Paiements Canada, 71&nbsp;% des entreprises ont re\u00e7u un remboursement total ou partiel pour les fonds qu\u2019elles ont perdus aux mains de fraudeurs.<\/p>\n\n\n\n<p>Comme les entreprises canadiennes pr\u00e9sentent un risque \u00e9lev\u00e9 d\u2019\u00eatre vis\u00e9es par ce type de fraude en ligne de plus en plus r\u00e9pandu, il est important qu\u2019elles se dotent d\u2019outils, de politiques et de protocoles de cybers\u00e9curit\u00e9 efficaces, et qu\u2019elles demeurent \u00e0 l\u2019aff\u00fbt des communications suspectes, m\u00eame celles qui semblent provenir de sources de confiance.<\/p>\n\n\n\n<p><strong>En savoir plus&nbsp;:<\/strong> <a href=\"https:\/\/www.rbc.com\/cyberfute\/comment-proteger-votre-entreprise\/index.html?_ot=1749762301382-1%3A1%2C2%3A1%2C3%3A1%2C4%3A1&amp;_gl=1*mkqsld*_gcl_au*MTQ3MjI4MDg3My4xNzQ1MjQwNDA5*_ga*NzM2MTI2MzkwLjE3NDUzNDk5NTc.*_ga_89NPCTDXQR*czE3NDk4NDA4MDMkbzM3MSRnMSR0MTc0OTg0MDg0NiRqMTckbDAkaDA.&amp;_ot=1749840850960-1%3A1%2C2%3A1%2C3%3A1%2C4%3A1\" data-dig-id=\"LP-36110-211eb8eb\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"La cybers\u00e9curit\u00e9 des petites entreprises\" class=\"rbc-link-format\">La cybers\u00e9curit\u00e9 des petites entreprises<\/a><\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse942faa40\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse942faa40\" data-dig-id=\"LP-32776-942faa40\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"Un mot de nos avocats\"><span>Un mot de nos avocats<\/span><span>Un mot de nos avocats<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse942faa40\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p>Le pr\u00e9sent article vise \u00e0 offrir des renseignements g\u00e9n\u00e9raux seulement et n\u2019a pas pour objet de fournir des conseils juridiques ou financiers, ni d\u2019autres conseils professionnels. Veuillez consulter un conseiller professionnel en ce qui concerne votre situation particuli\u00e8re. Les renseignements pr\u00e9sent\u00e9s sont r\u00e9put\u00e9s \u00eatre factuels et \u00e0 jour, mais nous ne garantissons pas leur exactitude et ils ne doivent pas \u00eatre consid\u00e9r\u00e9s comme une analyse exhaustive des sujets abord\u00e9s. Les opinions exprim\u00e9es refl\u00e8tent le jugement des auteurs \u00e0 la date de publication et peuvent changer. La Banque Royale du Canada et ses entit\u00e9s ne font pas la promotion, ni explicitement ni implicitement, des conseils, des avis, des renseignements, des produits ou des services de tiers.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Les organisations canadiennes re\u00e7oivent des messages qui semblent provenir de sources de confiance, mais qui \u00e9manent en fait de fraudeurs.<\/p>\n","protected":false},"author":319,"featured_media":36111,"parent":6578,"menu_order":0,"template":"wp-custom-template-mmm-sticky-nav","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"tags":[319,356],"rbc_content_type":[121],"rbc_audience":[164],"rbc_lob_group":[160,122],"rbc_difficulty_level":[162],"rbc_mmm_category":[32,53,48,99,33,114],"class_list":["post-36110","rbc_my_money_matter","type-rbc_my_money_matter","status-publish","has-post-thumbnail","hentry","tag-cybersecurite","tag-perspectives-secteur-commercial","rbc_content_type-article","rbc_audience-proprietaires-dentreprise","rbc_lob_group-cybersecurite","rbc_lob_group-entreprises","rbc_difficulty_level-intermediate","rbc_mmm_category-academie-financiere","rbc_mmm_category-conseils-daffaires-appropries","rbc_mmm_category-cybersecurite","rbc_mmm_category-cybersecurite-pour-les-entreprises","rbc_mmm_category-entreprises","rbc_mmm_category-secteur-commercial"],"acf":{"contently_publication_id":"","custom_author":"Jared Lindzon","rbc_video_header":"","rbc_media_duration":"","rbc_video_keywords":"","rbc_video_description":"","rbc_video_upload_date":"","rbc_toc_for_mmm_tag":"h2","rbc_toc_for_mmm_limit":6,"rbc_toc_for_mmm":null,"rbc_toc_for_mmm_action":"Generate Table Of Contents"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<meta name=\"description\" content=\"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:description\" content=\"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Banque Royale\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T18:30:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/\",\"name\":\"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin - Mes finances d\u2019abord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80\",\"datePublished\":\"2026-02-26T18:29:52+00:00\",\"dateModified\":\"2026-02-26T18:30:56+00:00\",\"description\":\"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80\",\"width\":6046,\"height\":4035,\"caption\":\"Un homme d\u2019affaires nerveux regarde son ordinateur portable dans un bureau\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mes finances d\u2019abord\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entreprises\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseils d\u2019affaires appropri\u00e9s\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Secteur commercial\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/\",\"name\":\"RBC Banque Royale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"description":"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","og_locale":"fr_FR","og_type":"article","og_description":"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.","og_url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","og_site_name":"RBC Banque Royale","article_modified_time":"2026-02-26T18:30:56+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80","twitter_misc":{"Est. reading time":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","name":"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin - Mes finances d\u2019abord","isPartOf":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/#primaryimage"},"image":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80","datePublished":"2026-02-26T18:29:52+00:00","dateModified":"2026-02-26T18:30:56+00:00","description":"En 2024, l\u2019usurpation d\u2019identit\u00e9 est devenue la forme de fraude en ligne la plus r\u00e9pandue et la plus co\u00fbteuse pour les entreprises canadiennes.","breadcrumb":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/#primaryimage","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80","contentUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80","width":6046,"height":4035,"caption":"Un homme d\u2019affaires nerveux regarde son ordinateur portable dans un bureau"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mes finances d\u2019abord","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/"},{"@type":"ListItem","position":2,"name":"Entreprises","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/"},{"@type":"ListItem","position":3,"name":"Conseils d\u2019affaires appropri\u00e9s","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/"},{"@type":"ListItem","position":4,"name":"Secteur commercial","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/"},{"@type":"ListItem","position":5,"name":"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin"}]},{"@type":"WebSite","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/","name":"RBC Banque Royale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbcroyalbank.com\/fr-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Protection de votre entreprise contre la fraude par usurpation d\u2019identit\u00e9 : la rep\u00e9rer et y mettre fin","url":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/conseils-daffaires-appropries\/secteur-commercial\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\/"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80&w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80"},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"jacobkeast"}],"creator":["jacobkeast"],"publisher":{"@type":"Organization","name":"RBC Banque Royale","logo":""},"keywords":["cybers\u00e9curit\u00e9","perspectives secteur commercial"],"dateCreated":"2026-02-26T18:29:52Z","datePublished":"2026-02-26T18:29:52Z","dateModified":"2026-02-26T18:30:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Protection de votre entreprise contre la fraude par usurpation d\\u2019identit\\u00e9 : la rep\\u00e9rer et y mettre fin\",\"url\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/conseils-daffaires-appropries\\\/secteur-commercial\\\/protection-de-votre-entreprise-contre-la-fraude-par-usurpation-didentite-la-reperer-et-y-mettre-fin\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80&w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"jacobkeast\"}],\"creator\":[\"jacobkeast\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC Banque Royale\",\"logo\":\"\"},\"keywords\":[\"cybers\\u00e9curit\\u00e9\",\"perspectives secteur commercial\"],\"dateCreated\":\"2026-02-26T18:29:52Z\",\"datePublished\":\"2026-02-26T18:29:52Z\",\"dateModified\":\"2026-02-26T18:30:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbcroyalbank.com\/p.js"},"featured_img":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/A-business-man-is-stressed-looking-at-his-laptop-in-an-office.jpg?quality=80&w=1024","coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/author\/jacobkeast\/","display_name":"jacobkeast"},"relative_dates":{"created":"Publi\u00e9 3 mois il y a","modified":"Mis \u00e0 jour 3 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 26 f\u00e9vrier 2026","modified":"Mise \u00e0 jour le 26 f\u00e9vrier 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 26 f\u00e9vrier 2026 6:29  ","modified":"Mise \u00e0 jour le 26 f\u00e9vrier 2026 6:30  "},"featured_img_caption":"","tax_additional":{"post_tag":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/cybersecurite\/\" class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/perspectives-secteur-commercial\/\" class=\"advgb-post-tax-term\">Perspectives secteur commercial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/span>","<span class=\"advgb-post-tax-term\">Perspectives secteur commercial<\/span>"],"slug":"post_tag","name":"\u00c9tiquettes"},"rbc_content_type":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/content-type\/article\/\" class=\"advgb-post-tax-term\">Article<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Article<\/span>"],"slug":"rbc_content_type","name":"Content Types"},"rbc_audience":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/audience\/proprietaires-d%c2%92entreprise\/\" class=\"advgb-post-tax-term\">Propri\u00e9taires d\u2019entreprise<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Propri\u00e9taires d\u2019entreprise<\/span>"],"slug":"rbc_audience","name":"Audiences"},"rbc_lob_group":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/lob-group\/cybersecurite\/\" class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/lob-group\/entreprises\/\" class=\"advgb-post-tax-term\">Entreprises<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/span>","<span class=\"advgb-post-tax-term\">Entreprises<\/span>"],"slug":"rbc_lob_group","name":"LOB Groups"},"rbc_difficulty_level":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/difficulty-level\/intermediate\/\" class=\"advgb-post-tax-term\">Intermediate<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Intermediate<\/span>"],"slug":"rbc_difficulty_level","name":"Difficulty Levels"},"rbc_mmm_category":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/academie-financiere\/\" class=\"advgb-post-tax-term\">Acad\u00e9mie financi\u00e8re<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/conseils-daffaires-appropries\/\" class=\"advgb-post-tax-term\">Conseils d\u2019affaires appropri\u00e9s<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/cybersecurite\/\" class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/cybersecurite-pour-les-entreprises\/\" class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9 pour les entreprises<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/entreprises\/\" class=\"advgb-post-tax-term\">Entreprises<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/secteur-commercial\/\" class=\"advgb-post-tax-term\">Secteur commercial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Acad\u00e9mie financi\u00e8re<\/span>","<span class=\"advgb-post-tax-term\">Conseils d\u2019affaires appropri\u00e9s<\/span>","<span class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9<\/span>","<span class=\"advgb-post-tax-term\">Cybers\u00e9curit\u00e9 pour les entreprises<\/span>","<span class=\"advgb-post-tax-term\">Entreprises<\/span>","<span class=\"advgb-post-tax-term\">Secteur commercial<\/span>"],"slug":"rbc_mmm_category","name":"Categories"},"ep_custom_result":{"linked":[],"unlinked":[],"slug":"ep_custom_result","name":"Custom Results"}},"series_order":"","jetpack_sharing_enabled":true,"primary_tag":"356","primary_rbc_mmm_category":"33","_links":{"self":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter"}],"about":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/types\/rbc_my_money_matter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/users\/319"}],"version-history":[{"count":8,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36110\/revisions"}],"predecessor-version":[{"id":37824,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36110\/revisions\/37824"}],"up":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media\/36111"}],"wp:attachment":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=36110"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/tags?post=36110"},{"taxonomy":"rbc_content_type","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_content_type?post=36110"},{"taxonomy":"rbc_audience","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_audience?post=36110"},{"taxonomy":"rbc_lob_group","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_lob_group?post=36110"},{"taxonomy":"rbc_difficulty_level","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_difficulty_level?post=36110"},{"taxonomy":"rbc_mmm_category","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_mmm_category?post=36110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}