{"id":36120,"date":"2025-07-23T16:31:51","date_gmt":"2025-07-23T16:31:51","guid":{"rendered":"https:\/\/www.rbcroyalbank.com\/fr-ca\/?post_type=rbc_my_money_matter&#038;p=36120"},"modified":"2025-07-23T16:37:05","modified_gmt":"2025-07-23T16:37:05","slug":"constituer-un-heritage-financier","status":"publish","type":"rbc_my_money_matter","link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","title":{"rendered":"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille"},"content":{"rendered":"\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<div class=\"wp-block-rbc-rbc-block drop-shadow pos-rel top-line-blue block-wpr  mar-b-hlf\">\n<div class=\"wp-block-rbc-rbc-block-inner-block block-inner pad-b-hlf\">\n<h4 class=\"wp-block-heading\" id=\"h-tlpl\">TLPL<\/h4>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-blue-disc\">\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\">Les parents veulent offrir un avenir s\u00fbr et rempli de possibilit\u00e9s \u00e0 leurs enfants\u00a0\u2013\u00a0et pour y parvenir, il faut effectuer une planification financi\u00e8re, surtout en p\u00e9riode d\u2019incertitude \u00e9conomique.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-blue-disc\">\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\">La constitution d\u2019un patrimoine commence d\u00e8s la vingtaine et la trentaine. La cl\u00e9 du succ\u00e8s est d\u2019adopter de bonnes habitudes, par exemple, utiliser un budget.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-blue-disc\">\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\">Laisser un h\u00e9ritage, c\u2019est aussi transmettre ses valeurs et ses le\u00e7ons de vie, notamment en inculquant des connaissances financi\u00e8res \u00e0 ses enfants et en faisant des dons de bienfaisance.<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ce que veulent les parents avant tout, c\u2019est offrir \u00e0 leurs enfants un avenir stable et riche de possibilit\u00e9s. C\u2019est ce qui les motive \u00e0 se lever chaque matin et \u00e0 avancer&nbsp;(\u00e7a, et un bon caf\u00e9). Comme les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes, ils travaillent dur pour offrir \u00e0 leurs enfants ce qu\u2019ils n\u2019ont pas eu la chance de conna\u00eetre. Beaucoup de gens veulent que leurs enfants puissent avoir une \u00e9ducation excellente, des exp\u00e9riences enrichissantes et un avenir financier stable. Mais ce n\u2019est pas une mince t\u00e2che, surtout dans un contexte \u00e9conomique difficile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour constituer un patrimoine familial et laisser un h\u00e9ritage qui rend fier, il faut poser des gestes d\u00e9lib\u00e9r\u00e9s \u00e0 chaque \u00e9tape de la vie. Voici donc cinq fa\u00e7ons de constituer un patrimoine pour assurer l\u2019avenir de votre famille.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-1-adopter-de-bonnes-habitudes-financieres\">1. Adopter de bonnes habitudes financi\u00e8res<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est dans la vingtaine et la trentaine que vous \u00e9tablirez les bases de votre succ\u00e8s. Comme vous n\u2019avez peut-\u00eatre pas encore beaucoup d\u2019obligations financi\u00e8res, c\u2019est le moment id\u00e9al pour am\u00e9liorer vos comp\u00e9tences et gagner en confiance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est important d\u2019avoir un revenu suffisant pour couvrir ses d\u00e9penses, mais les bonnes habitudes financi\u00e8res le sont tout autant. Dans un&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/academie-financiere\/connaissances-financieres-de-base\/rapport-a-largent\/sante-financiere-prenez-de-bonnes-habitudes\/\">sondage r\u00e9cent de RBC<\/a>, plus du tiers des r\u00e9pondants ont avou\u00e9 qu\u2019ils n\u2019ont pas d\u2019objectifs financiers (38&nbsp;%), ne font pas de planification financi\u00e8re (37&nbsp;%) et ne surveillent pas leurs d\u00e9penses (34&nbsp;%). C\u2019est pourtant la base d\u2019une bonne gestion des finances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prenez le temps d\u2019apprendre \u00e0 faire un budget. Certaines r\u00e8gles pourront vous aider, par exemple celle des&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/academie-financiere\/connaissances-financieres-de-base\/etablissement-du-budget\/saine-gestion-de-son-argent-conseils-pour-un-budget-adapte-a-votre-situation\/\">50\/30\/20<\/a>, mais l\u2019essentiel est de cr\u00e9er un budget r\u00e9aliste qui fonctionne pour vous. Si vous pr\u00e9f\u00e9rez une solution num\u00e9rique, l\u2019outil&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/mobile\/feature\/nomi\/budgets\/\">NOMI de RBC<\/a>&nbsp;peut vous recommander un budget selon vos habitudes de consommation et d\u2019\u00e9pargne (et peut vous aider \u00e0 le respecter par la suite). Faire un budget est une habitude qui rapporte. Selon l\u2019<a href=\"https:\/\/www.canada.ca\/fr\/agence-consommation-matiere-financiere\/programmes\/recherche\/enquete-canadienne-capacites-financieres-2019.html\">Enqu\u00eate canadienne sur les capacit\u00e9s financi\u00e8res<\/a>, les gens qui font un budget sont moins susceptibles de manquer \u00e0 leurs engagements financiers.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ils ont notamment moins tendance \u00e0 d\u00e9passer leur revenu mensuel ou \u00e0 avoir besoin d\u2019emprunter pour leurs d\u00e9penses quotidiennes. En ayant un meilleur portrait de vos habitudes de consommation, vous pourrez vous ajuster si n\u00e9cessaire. Le montant que vous d\u00e9pensez en livres vous surprend&nbsp;? Il est peut-\u00eatre temps de vous abonner \u00e0 la biblioth\u00e8que.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vingtaine et la trentaine sont aussi le moment id\u00e9al pour ouvrir un&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr\/placements\/celi.html\">compte d\u2019\u00e9pargne libre d\u2019imp\u00f4t<\/a>&nbsp;(CELI) et un&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr\/placements\/reer.html\">r\u00e9gime enregistr\u00e9 d\u2019\u00e9pargne-retraite<\/a>&nbsp;(REER). Si vous aimeriez un jour devenir propri\u00e9taire, un&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr\/placements\/celiapp.html\">compte d\u2019\u00e9pargne libre d\u2019imp\u00f4t pour l\u2019achat d\u2019une premi\u00e8re propri\u00e9t\u00e9<\/a>&nbsp;(CELIAPP) pourra vous aider \u00e0 atteindre cet objectif. Pour commencer \u00e0 faire cro\u00eetre votre \u00e9pargne dans ces comptes, vous pourriez \u00e9tablir des&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/academie-financiere\/connaissances-financieres-de-base\/etablissement-du-budget\/cotisations-preautorisees\/\">contributions pr\u00e9autoris\u00e9es<\/a>&nbsp;(CPA) afin de mettre de c\u00f4t\u00e9 un montant fixe chaque mois, sans avoir besoin d\u2019y penser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et si vous avez d\u00e9pass\u00e9 la trentaine, il n\u2019est pas trop tard pour adopter de meilleures habitudes et profiter des avantages d\u2019un budget et de l\u2019\u00e9pargne. En effet, les \u00e9tudes indiquent que \u00e7a en vaut la peine. Il y a un lien entre bonnes habitudes financi\u00e8res et bien-\u00eatre g\u00e9n\u00e9ral, c\u2019est-\u00e0-dire moins de stress, un meilleur sommeil et des relations personnelles solides.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-2-se-fixer-des-objectifs\">2. Se fixer des objectifs<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mettre ses objectifs sur papier est une excellente fa\u00e7on de rester sur la bonne voie. Et puis, c\u2019est quand m\u00eame agr\u00e9able de r\u00eaver et de planifier. Vous aimeriez d\u00e9marrer une entreprise, devenir propri\u00e9taire, organiser un grand mariage, fonder une famille, faire le tour du monde&nbsp;? Si vous avez une vision claire de vos objectifs, vous pourrez prendre de meilleures d\u00e9cisions financi\u00e8res.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il peut \u00eatre utile de diviser vos objectifs en cat\u00e9gories&nbsp;: \u00e0 court terme (ex.&nbsp;: constituer un fonds d\u2019urgence), \u00e0 moyen terme (ex.&nbsp;: \u00e9pargner pour une voiture ou une mise de fonds) et \u00e0 long terme (ex.&nbsp;: financer les \u00e9tudes de vos enfants ou votre retraite).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous voulons tous \u00eatre \u00e0 l\u2019abri du besoin \u00e0 la retraite. Quelle que soit votre vision, assurez-vous d\u2019avoir un plan. D\u2019apr\u00e8s un&nbsp;<a href=\"https:\/\/www.canada.ca\/fr\/agence-consommation-matiere-financiere\/programmes\/recherche\/enquete-canadienne-capacites-financieres-2019.html\">sondage national<\/a>, les Canadiens qui n\u2019ont pas de plan d\u2019\u00e9pargne pour la retraite sont particuli\u00e8rement anxieux par rapport \u00e0 cette \u00e9tape de la vie.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vos objectifs \u00e9volueront au fil du temps, alors gardez votre plan \u00e0 jour et laissez-vous inspirer par tout ce que l\u2019avenir vous r\u00e9serve.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-3-demander-conseil-a-des-professionnels\">3. Demander conseil \u00e0 des professionnels<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La constitution d\u2019un h\u00e9ritage est tout un projet. Il faut s\u2019entourer de gens qui peuvent aider. Nombreux sont les investisseurs qui disent que leur conseiller les a aid\u00e9s \u00e0 am\u00e9liorer leurs habitudes d\u2019\u00e9pargne et de placement et \u00e0 \u00e9viter les erreurs qui peuvent co\u00fbter cher. Si vous \u00eates pr\u00eat \u00e0 choisir un conseiller,&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/investisseur-inspire\/academie-des-placements\/guide-complet-pour-choisir-un-conseiller-en-services-financiers\/\">voici un guide pour vous aider \u00e0 arr\u00eater votre choix<\/a>. Savoir \u00e9gale pouvoir, et votre conseiller vous donnera acc\u00e8s \u00e0 un pr\u00e9cieux r\u00e9seau de personnes-ressources et de renseignements. Il pourra par exemple vous informer des nouveaux produits, vous offrir des conseils judicieux au moment opportun, et vous renseigner sur l\u2019\u00e9tat des march\u00e9s. Vous avez une question&nbsp;? Il suffit d\u2019un appel. Et au fur et \u00e0 mesure que votre situation financi\u00e8re \u00e9voluera, votre conseiller vous aidera \u00e0 trouver des solutions et \u00e0 mettre en \u0153uvre un plan qui vous convient. Ce n\u2019est pas un hasard si 76&nbsp;% des investisseurs qui font affaire avec un conseiller financier disent ressentir un&nbsp;<a href=\"https:\/\/www.rbcgam.com\/fr\/ca\/learn-plan\/investment-basics\/the-value-of-working-with-a-financial-advisor\/detail\">sentiment de bien-\u00eatre<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensez \u00e0 mettre sur pied \u00ab&nbsp;votre&nbsp;\u00bb \u00e9quipe&nbsp;: d\u2019autres professionnels pourront vous donner des conseils pr\u00e9cieux, comme un comptable, un courtier hypoth\u00e9caire, un fiscaliste ou un planificateur successoral.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-4-inculquer-a-ses-enfants-des-connaissances-financieres\">4. Inculquer \u00e0 ses enfants des connaissances financi\u00e8res<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous constituez un patrimoine pour vos enfants, il est tout \u00e0 fait logique de leur apprendre \u00e0 le g\u00e9rer. N\u2019attendez pas qu\u2019ils grandissent. En leur transmettant de bonnes habitudes \u00e0 un jeune \u00e2ge, vous leur donnerez des outils pour respecter l\u2019argent toute leur vie.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-voici-quelques-facons-d-enseigner-de-bonnes-habitudes-financieres-a-vos-enfants\">Voici quelques fa\u00e7ons d\u2019enseigner de bonnes habitudes financi\u00e8res \u00e0 vos enfants\u00a0:\u00a0<\/h3>\n\n\n\n<ul class=\"wp-block-rbc-list default is-style-blue-disc\">\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\"><strong>Jeunes enfants\u00a0:<\/strong>\u00a0Profitez des moments du quotidien pour leur parler d\u2019argent de mani\u00e8re neutre et factuelle. Montrez-leur les prix, montrez-leur les billets et la monnaie dans votre portefeuille, et invitez-les \u00e0 vous aider \u00e0 compter le montant \u00e0 payer. S\u2019ils ont de l\u2019argent de poche ou ont re\u00e7u somme \u00e0 leur anniversaire ou aux f\u00eates, faites-leur d\u00e9couvrir le plaisir d\u2019\u00e9pargner pour un jouet sp\u00e9cial.\u00a0<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\"><strong>Adolescents\u00a0:<\/strong>\u00a0Incluez-les dans les discussions financi\u00e8res familiales, comme la pr\u00e9paration d\u2019un budget pour des vacances ou des r\u00e9novations. Montrez-leur comment lire un relev\u00e9 financier et payer une carte de cr\u00e9dit \u00e0 temps. Si vous les aidez \u00e0 faire certaines d\u00e9penses (v\u00eatements, sorties, etc.), passez-les en revue ensemble chaque mois. Ce sera une excellente fa\u00e7on pour eux de devenir financi\u00e8rement responsables. Et quand ils commenceront \u00e0 gagner leur propre argent, vous pourrez suivre leurs d\u00e9penses et les guider gr\u00e2ce \u00e0 la\u00a0<a href=\"https:\/\/www.mydoh.ca\/fr\/\">carte \u00e0 puce pr\u00e9pay\u00e9e Mydoh<\/a>.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p class=\"wp-block-paragraph\"><strong>Jeunes adultes\u00a0:<\/strong>\u00a0Toute la famille gagne \u00e0 communiquer ouvertement. Si vous avez l\u2019intention d\u2019aider un enfant adulte \u00e0 faire un achat important, comme une premi\u00e8re maison, discutez des d\u00e9tails ensemble. Allez-vous contribuer \u00e0 la mise de fonds\u00a0? Qui payera les droits de cession immobili\u00e8re\u00a0? Et les frais des r\u00e9parations n\u00e9cessaires\u00a0? Ayez une discussion approfondie pour fournir un encadrement et fixer des limites.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-5-transferer-son-patrimoine\">5. Transf\u00e9rer son patrimoine<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les derni\u00e8res \u00e9tapes de la vie sont parfois les plus gratifiantes, puisque c\u2019est l\u00e0 que les efforts que vous avez d\u00e9ploy\u00e9s pour b\u00e2tir votre h\u00e9ritage porteront leurs fruits. On voit de plus en plus de parents \u00e2g\u00e9s commencer \u00e0&nbsp;<a href=\"https:\/\/www.rbcwealthmanagement.com\/fr-ca\/insights\/leguer-son-patrimoine-de-son-vivant-plutot-qua-travers-son-testament-a-son-deces\">donner de l\u2019argent de leur vivant<\/a>, plut\u00f4t qu\u2019apr\u00e8s leur d\u00e9c\u00e8s, afin de pouvoir en constater les bienfaits. Ce genre de soutien peut offrir une pr\u00e9cieuse marge de man\u0153uvre financi\u00e8re aux enfants adultes, surtout dans un contexte \u00e9conomique difficile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette \u00e9tape est \u00e9galement une occasion de transmettre vos valeurs. Vous pouvez faire des dons de bienfaisance \u00e0 des causes qui vous tiennent \u00e0 c\u0153ur, \u00e0 vous et \u00e0 votre famille, et expliquer votre d\u00e9marche \u00e0 la prochaine g\u00e9n\u00e9ration, afin qu\u2019elle puisse profiter de votre v\u00e9cu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est essentiel d\u2019<a href=\"https:\/\/www.rbcroyalbank.com\/en-ca\/my-money-matters\/life-events\/finances-and-relationships\/death-of-a-family-member\/the-9-reasons-you-need-a-will\/\" target=\"_blank\" rel=\"noreferrer noopener\">avoir un testament<\/a>&nbsp;\u00e0&nbsp;chaque \u00e9tape de la vie et de le garder \u00e0 jour. Votre testament peut avoir des effets durables. Sur le plan financier, il vous permet de planifier de mani\u00e8re efficace, notamment en mati\u00e8re de fiscalit\u00e9. De plus, il vous permet d\u2019\u00e9viter d\u2019imposer \u00e0 vos proches des d\u00e9cisions difficiles susceptibles d\u2019entra\u00eener des conflits.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-le-bon-moment-pour-le-bon-plan\">Le bon moment pour le bon plan\u00a0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La constitution d\u2019un h\u00e9ritage est un processus qui s\u2019\u00e9tale sur toute une vie et qui comprend de nombreuses \u00e9tapes. C\u2019est un geste d\u2019amour, parce que vous voulez que vos enfants et petits-enfants ne manquent de rien. Et c\u2019est une t\u00e2che qui semble plus urgente que jamais, dans une \u00e9conomie en constante \u00e9volution. Peu importe l\u2019\u00e9tape o\u00f9 vous vous trouvez, prenez rendez-vous avec un&nbsp;<a href=\"https:\/\/www.rbcroyalbank.com\/fr\/placements\/bienvenue\/get-advice.html\" target=\"_blank\" rel=\"noreferrer noopener\">conseiller financier RBC<\/a>&nbsp;pour explorer les options qui pourraient vous convenir.<\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse942faa40\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse942faa40\" data-dig-id=\"LP-36120-942faa40\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"Un mot de nos avocats\"><span>Un mot de nos avocats<\/span><span>Un mot de nos avocats<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse942faa40\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p class=\"wp-block-paragraph\">Le pr\u00e9sent article vise \u00e0 offrir des renseignements g\u00e9n\u00e9raux seulement et n\u2019a pas pour objet de fournir des conseils juridiques ou financiers, ni d\u2019autres conseils professionnels. Veuillez consulter un conseiller professionnel en ce qui concerne votre situation particuli\u00e8re. Les renseignements pr\u00e9sent\u00e9s sont r\u00e9put\u00e9s \u00eatre factuels et \u00e0 jour, mais nous ne garantissons pas leur exactitude et ils ne doivent pas \u00eatre consid\u00e9r\u00e9s comme une analyse exhaustive des sujets abord\u00e9s. Les opinions exprim\u00e9es refl\u00e8tent le jugement des auteurs \u00e0 la date de publication et peuvent changer. La Banque Royale du Canada et ses entit\u00e9s ne font pas la promotion, ni explicitement ni implicitement, des conseils, des avis, des renseignements, des produits ou des services de tiers.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Pour constituer un patrimoine familial et laisser un h\u00e9ritage qui rend fier, il faut poser des gestes d\u00e9lib\u00e9r\u00e9s \u00e0 chaque \u00e9tape de la vie.<\/p>\n","protected":false},"author":132,"featured_media":36123,"parent":6546,"menu_order":0,"template":"wp-custom-template-mmm-sticky-nav","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":""},"tags":[362,152,306,130,365,138],"rbc_content_type":[121],"rbc_audience":[139],"rbc_lob_group":[140],"rbc_difficulty_level":[123],"rbc_mmm_category":[31,42,264,169,83],"rbc_mmm_author":[],"class_list":["post-36120","rbc_my_money_matter","type-rbc_my_money_matter","status-publish","has-post-thumbnail","hentry","tag-academie-des-placements","tag-education","tag-famille","tag-finances-personnelles","tag-gestion-de-largent-2","tag-parentalite","rbc_content_type-article","rbc_audience-parents","rbc_lob_group-placements","rbc_difficulty_level-beginner","rbc_mmm_category-evenements-de-la-vie","rbc_mmm_category-finances-et-relations","rbc_mmm_category-idees-et-motivation","rbc_mmm_category-investisseur-inspire","rbc_mmm_category-parentalite"],"acf":{"contently_publication_id":"","custom_author":"Sonya Bell","rbc_video_header":"","rbc_media_duration":"","rbc_video_keywords":"","rbc_video_description":"","rbc_video_upload_date":"","rbc_toc_for_mmm_tag":"h2","rbc_toc_for_mmm_limit":6,"rbc_toc_for_mmm":null,"rbc_toc_for_mmm_action":"Generate Table Of Contents"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<meta name=\"description\" content=\"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:description\" content=\"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Banque Royale\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T16:37:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/\",\"name\":\"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille - Mes finances d\u2019abord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/shutterstock_1840855456.jpg\",\"datePublished\":\"2025-07-23T16:31:51+00:00\",\"dateModified\":\"2025-07-23T16:37:05+00:00\",\"description\":\"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/shutterstock_1840855456.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/shutterstock_1840855456.jpg\",\"width\":5184,\"height\":3456,\"caption\":\"Silhouette d\u2019un p\u00e8re et de son fils heureux jouant au coucher du soleil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mes finances d\u2019abord\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements de la Vie\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Finances et relations\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Parentalit\u00e9\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/\",\"name\":\"RBC Banque Royale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"description":"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","og_locale":"fr_FR","og_type":"article","og_description":"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.","og_url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","og_site_name":"RBC Banque Royale","article_modified_time":"2025-07-23T16:37:05+00:00","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","name":"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille - Mes finances d\u2019abord","isPartOf":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/#primaryimage"},"image":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg","datePublished":"2025-07-23T16:31:51+00:00","dateModified":"2025-07-23T16:37:05+00:00","description":"Laisser un h\u00e9ritage aux g\u00e9n\u00e9rations futures est un processus qui commence d\u00e8s l\u2019\u00e2ge adulte. Vous pouvez b\u00e2tir un patrimoine et parfaire vos connaissances financi\u00e8res \u00e0 chaque \u00e9tape de la vie pour offrir \u00e0 vos proches un avenir s\u00fbr et riche de possibilit\u00e9s.","breadcrumb":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/#primaryimage","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg","contentUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg","width":5184,"height":3456,"caption":"Silhouette d\u2019un p\u00e8re et de son fils heureux jouant au coucher du soleil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mes finances d\u2019abord","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements de la Vie","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/"},{"@type":"ListItem","position":3,"name":"Finances et relations","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/"},{"@type":"ListItem","position":4,"name":"Parentalit\u00e9","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/"},{"@type":"ListItem","position":5,"name":"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille"}]},{"@type":"WebSite","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/","name":"RBC Banque Royale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbcroyalbank.com\/fr-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Investir dans son h\u00e9ritage : cinq fa\u00e7ons de constituer un patrimoine pour l\u2019avenir de sa famille","url":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/evenements-de-la-vie\/finances-et-relations\/parentalite\/constituer-un-heritage-financier\/"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg?quality=80&w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg"},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"RBC"}],"creator":["RBC"],"publisher":{"@type":"Organization","name":"RBC Banque Royale","logo":""},"keywords":["acad\u00e9mie des placements","\u00e9ducation","famille","finances personnelles","gestion de l\u2019argent","parentalit\u00e9"],"dateCreated":"2025-07-23T16:31:51Z","datePublished":"2025-07-23T16:31:51Z","dateModified":"2025-07-23T16:37:05Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Investir dans son h\\u00e9ritage : cinq fa\\u00e7ons de constituer un patrimoine pour l\\u2019avenir de sa famille\",\"url\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/evenements-de-la-vie\\\/finances-et-relations\\\/parentalite\\\/constituer-un-heritage-financier\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/shutterstock_1840855456.jpg?quality=80&w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2025\\\/06\\\/shutterstock_1840855456.jpg\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"RBC\"}],\"creator\":[\"RBC\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC Banque Royale\",\"logo\":\"\"},\"keywords\":[\"acad\\u00e9mie des placements\",\"\\u00e9ducation\",\"famille\",\"finances personnelles\",\"gestion de l\\u2019argent\",\"parentalit\\u00e9\"],\"dateCreated\":\"2025-07-23T16:31:51Z\",\"datePublished\":\"2025-07-23T16:31:51Z\",\"dateModified\":\"2025-07-23T16:37:05Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbcroyalbank.com\/p.js"},"featured_img":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2025\/06\/shutterstock_1840855456.jpg?quality=80&w=1024","coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/author\/wordpress\/","display_name":"RBC"},"relative_dates":{"created":"Publi\u00e9 1 an il y a","modified":"Mis \u00e0 jour 1 an il y a"},"absolute_dates":{"created":"Publi\u00e9 le 23 juillet 2025","modified":"Mise \u00e0 jour le 23 juillet 2025"},"absolute_dates_time":{"created":"Publi\u00e9 le 23 juillet 2025 4:31  ","modified":"Mise \u00e0 jour le 23 juillet 2025 4:37  "},"featured_img_caption":"","tax_additional":{"post_tag":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/academie-des-placements\/\" class=\"advgb-post-tax-term\">Acad\u00e9mie des placements<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/education\/\" class=\"advgb-post-tax-term\">\u00c9ducation<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/famille\/\" class=\"advgb-post-tax-term\">Famille<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/finances-personnelles\/\" class=\"advgb-post-tax-term\">Finances personnelles<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/gestion-de-largent-2\/\" class=\"advgb-post-tax-term\">Gestion de l\u2019argent<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/parentalite\/\" class=\"advgb-post-tax-term\">Parentalit\u00e9<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Acad\u00e9mie des placements<\/span>","<span class=\"advgb-post-tax-term\">\u00c9ducation<\/span>","<span class=\"advgb-post-tax-term\">Famille<\/span>","<span class=\"advgb-post-tax-term\">Finances personnelles<\/span>","<span class=\"advgb-post-tax-term\">Gestion de l\u2019argent<\/span>","<span class=\"advgb-post-tax-term\">Parentalit\u00e9<\/span>"],"slug":"post_tag","name":"\u00c9tiquettes"},"rbc_content_type":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/content-type\/article\/\" class=\"advgb-post-tax-term\">Article<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Article<\/span>"],"slug":"rbc_content_type","name":"Content Types"},"rbc_audience":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/audience\/parents\/\" class=\"advgb-post-tax-term\">Parents<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Parents<\/span>"],"slug":"rbc_audience","name":"Audiences"},"rbc_lob_group":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/lob-group\/placements\/\" class=\"advgb-post-tax-term\">Placements<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Placements<\/span>"],"slug":"rbc_lob_group","name":"LOB Groups"},"rbc_difficulty_level":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/difficulty-level\/beginner\/\" class=\"advgb-post-tax-term\">Beginner<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Beginner<\/span>"],"slug":"rbc_difficulty_level","name":"Difficulty Levels"},"rbc_mmm_category":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/evenements-de-la-vie\/\" class=\"advgb-post-tax-term\">\u00c9v\u00e9nements de la Vie<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/finances-et-relations\/\" class=\"advgb-post-tax-term\">Finances et relations<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/idees-et-motivation\/\" class=\"advgb-post-tax-term\">Id\u00e9es et motivation<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/investisseur-inspire\/\" class=\"advgb-post-tax-term\">Investisseur inspir\u00e9<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/parentalite\/\" class=\"advgb-post-tax-term\">Parentalit\u00e9<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">\u00c9v\u00e9nements de la Vie<\/span>","<span class=\"advgb-post-tax-term\">Finances et relations<\/span>","<span class=\"advgb-post-tax-term\">Id\u00e9es et motivation<\/span>","<span class=\"advgb-post-tax-term\">Investisseur inspir\u00e9<\/span>","<span class=\"advgb-post-tax-term\">Parentalit\u00e9<\/span>"],"slug":"rbc_mmm_category","name":"Categories"},"rbc_mmm_author":{"linked":[],"unlinked":[],"slug":"rbc_mmm_author","name":"RBC MMM Authors"},"ep_custom_result":{"linked":[],"unlinked":[],"slug":"ep_custom_result","name":"Custom Results"}},"series_order":"","jetpack_sharing_enabled":true,"primary_tag":"138","primary_rbc_mmm_category":"83","_links":{"self":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter"}],"about":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/types\/rbc_my_money_matter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/users\/132"}],"version-history":[{"count":6,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36120\/revisions"}],"predecessor-version":[{"id":36439,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/36120\/revisions\/36439"}],"up":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media\/36123"}],"wp:attachment":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=36120"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/tags?post=36120"},{"taxonomy":"rbc_content_type","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_content_type?post=36120"},{"taxonomy":"rbc_audience","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_audience?post=36120"},{"taxonomy":"rbc_lob_group","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_lob_group?post=36120"},{"taxonomy":"rbc_difficulty_level","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_difficulty_level?post=36120"},{"taxonomy":"rbc_mmm_category","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_mmm_category?post=36120"},{"taxonomy":"rbc_mmm_author","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_mmm_author?post=36120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}