{"id":6954,"date":"2023-02-24T00:00:00","date_gmt":"2023-02-24T00:00:00","guid":{"rendered":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/"},"modified":"2024-02-23T19:49:59","modified_gmt":"2024-02-23T19:49:59","slug":"shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction","status":"publish","type":"rbc_my_money_matter","link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","title":{"rendered":"Shauna Curry s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&rsquo;action"},"content":{"rendered":"<div class=\"wp-block-rbc-single-article-header\">\n\t<section class=\"section-grey cover pad-t-hlf\">\n\t\t<div class=\"section-inner w-half w-mob-full centered-margin cover section-grey pad-tb-0\">\n\t\t\t\t\t\t\t<div class=\"inline-block pill-container pill-taxonomies\">\n\t\t\t\t\t<div class=\"mar-b-hlf mob-mar-b snipe pill is-style-blue-pill\">\n\t\t\t\t\t\t<a class=\"primary-taxonomy\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/communaute\/\">\n\t\t\t\t\t\t\t<span>Communaut\u00e9<\/span>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<h1 class=\"mar-b-hlf mar-t-0 mob-pad-lr-hlf h2 has-black-color\">Shauna Curry s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&rsquo;action<\/h1><p class=\"mar-b-0 mob-pad-lr-hlf author-text\">By Diane Amato<\/p>\t\t\t\t\t<div class=\"featured-image-wrapper pos-rel\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"620\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80\" class=\" cover-image  wp-post-image\" alt=\"Shauna Curry\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg 930w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?resize=300,200 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?resize=768,512 768w\" sizes=\"auto, (max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t<\/section>\n\t<div class=\"article mar-t-dbl\">\n\t\t\t\t<section>\n\t\t\t<div class=\"section-inner socials-section\">\n\t\t\t\t<div class=\"top-socials-bar mob-mar-b-hlf\">    <div class=\"social-links mob-mar-b-hlf mob-mar-t-hlf\">\n            <a class=\"social-button-wrapper sharing-custom sharing-email\" href=\"mailto:?subject=Shauna Curry s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&rsquo;action &#038;body=Bonjour, je pensais que cet article de RBC Mes finances d\u2019abord pourrait vous int\u00e9resser: https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\">\n        <img decoding=\"async\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/plugins\/rbc-blocks\/assets\/img\/icons\/icon-email.svg\"\n          alt=\"envelope icon\">\n        <span>\n          Courriel        <\/span>\n      <\/a>\n      <div class=\"social-button-wrapper sharing-copy-wrapper\">\n        <button class=\"sharing-custom sharing-copy\" data-url=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\">\n          <img decoding=\"async\"\n            src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/plugins\/rbc-blocks\/assets\/img\/icons\/icon-related.svg\"\n            alt=\"copy icon\">\n          <span id=\"sharing-copyUrl-Label\">\n            Copier l\u2019URL          <\/span>\n        <\/button>\n        <input type=\"text\" class=\"sharing-copy-text\" aria-labelledby=\"sharing-copyUrl-Label\">\n      <\/div>\n    <\/div>\n  <\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section>\n\t\t\t<div class=\"section-inner w-half w-mob-full centered-margin pad-tb-0 mob-mar-t-hlf mob-mar-b\">\n\t\t\t\t<p class=\"cover-pub-line text-xs mar-b-hlf\">Published 24 f\u00e9vrier 2023 \u2022 7 min de lecture<\/p>\t\t\t<\/div>\n\t\t<\/section>\n\t<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner w-half w-mob-full\" style=\"border-radius:0x\">\n<p class=\"wp-block-paragraph\"><i>Depuis plus de trois d\u00e9cennies,<a href=\"https:\/\/www.womenofinfluence.ca\/2022\/11\/24\/les-laureates-des-prix-canadiens-de-lentrepreneuriat-feminin-rbc-2022-sont-annonces\/\" target=\"_blank\" rel=\"noopener\">les Prix canadiens de l&rsquo;entrepreneuriat f\u00e9minin RBC<\/a> soulignent et c\u00e9l\u00e8brent les r\u00e9alisations des femmes les plus accomplies et les plus influentes du Canada. Pr\u00e9sent\u00e9s par Femmes d&rsquo;influence, les prix tournent les projecteurs vers des femmes qui jouent un r\u00f4le de premi\u00e8re importance dans la r\u00e9ussite des affaires au pays. \u00c0 l&rsquo;occasion de la Journ\u00e9e internationale des femmes, nous sommes fiers de faire conna\u00eetre le parcours inspirant de ces femmes.<\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Shauna Curry, cheffe de la direction <a href=\"https:\/\/www.cawst.org\/\" target=\"_blank\" rel=\"noopener\">du Centre for Affordable Water and Sanitation Technology (CAWST)<\/a>, a \u00e9t\u00e9 finaliste du <i>Prix de l&rsquo;\u00e9volution sociale : Influence nationale<\/i> dans le cadre des Prix canadiens de l&rsquo;entrepreneuriat RBC 2022. Toutefois, c&rsquo;est vraiment sur la sc\u00e8ne internationale que sa contribution se fait sentir. Depuis qu&rsquo;elle est en poste, elle a dirig\u00e9 la conception et l&rsquo;expansion de la prestation de services du CAWST, dont le r\u00e9seau comprend maintenant 420 organismes r\u00e9partis dans 100 pays, contre seulement deux au d\u00e9part. Rien qu&rsquo;en 2021, ces organismes ont permis d&rsquo;am\u00e9liorer la qualit\u00e9 de l&rsquo;eau et des installations sanitaires pour plus de cinq millions de personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab CAWST s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, soit l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau potable \u00bb, a expliqu\u00e9 M<sup>me<\/sup> Curry lors d&rsquo;un r\u00e9cent entretien. \u00ab L&rsquo;eau est \u00e9videmment essentielle \u00e0 notre sant\u00e9 et \u00e0 notre existence m\u00eame. Partout dans le monde, l&rsquo;eau est de plus en plus contamin\u00e9e et de moins en moins accessible, quel qu&rsquo;en soit l&rsquo;usage. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son cr\u00e9neau ax\u00e9 sur l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau potable, le CAWST se distingue par son mod\u00e8le d&rsquo;affaires, son approche et ses r\u00e9sultats. Son mod\u00e8le hybride, qui combine une soci\u00e9t\u00e9 d&rsquo;ing\u00e9nierie et un organisme de bienfaisance canadien enregistr\u00e9, lui permet, d&rsquo;une part, d&rsquo;offrir de la formation, des conseils et du soutien aux organismes pour qu&rsquo;ils mettent en \u0153uvre leurs propres solutions d&rsquo;assainissement et d&rsquo;alimentation en eau et, d&rsquo;autre part, de subventionner leurs services puisque la majorit\u00e9 d&rsquo;entre eux ne disposent pas des fonds n\u00e9cessaires pour les financer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En offrant un acc\u00e8s libre \u00e0 des ressources en ligne, \u00e0 des ateliers de formation virtuels et \u00e0 des services en personne, le CAWST montre aux gens comment avoir de l&rsquo;eau potable, des installations sanitaires et de bonnes conditions d&rsquo;hygi\u00e8ne dans leur propre foyer gr\u00e2ce \u00e0 des technologies simples et abordables. \u00ab Quand les gens entendent parler de notre mission, ils font un parall\u00e8le avec l&rsquo;adage \u201cQuand un homme a faim, mieux vaut lui apprendre \u00e0 p\u00eacher que de lui donner un poisson\u00a0\u00bb. En fait, c&rsquo;est bien plus que cela. Nous aidons les organismes et les collectivit\u00e9s \u00e0 choisir, \u00e0 \u00e9laborer et \u00e0 r\u00e9parer des solutions techniques qui leur permettront d&rsquo;avoir, de contr\u00f4ler et de pr\u00e9server un acc\u00e8s \u00e0 l&rsquo;eau potable \u00bb, affirme M<sup>me<\/sup> Curry.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La force int\u00e9rieure : la vie des gens et les collectivit\u00e9s changent quand on donne aux femmes les moyens d&rsquo;agir<b><\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><i>\u00c0 RBC, la Journ\u00e9e internationale des femmes 2023 a pour th\u00e8me C\u00e9l\u00e9brer sa force int\u00e9rieure<\/i><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le CAWST collabore avec des femmes et des hommes qui \u0153uvrent dans des organismes aux quatre coins du monde, mais M<sup>me<\/sup> Curry remarque que ce sont principalement les femmes qui sont \u00e0 la pointe du combat pour l&rsquo;acc\u00e8s \u00e0 l&rsquo;eau potable dans leur collectivit\u00e9. \u00ab En g\u00e9n\u00e9ral, ce sont les femmes qui sont responsables du foyer, et donc de l&rsquo;approvisionnement en eau. Si une femme sait que c&rsquo;est l&rsquo;eau qui a caus\u00e9 la mort de ses enfants ou les a rendus malades \u2013 et sait qu&rsquo;une solution existe \u2013 elle agit imm\u00e9diatement. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle donne l&rsquo;exemple frappant de six femmes en Ha\u00efti qui ont d\u00e9couvert par l&rsquo;entremise d&rsquo;un organisme local form\u00e9 par le CAWST que le d\u00e9c\u00e8s d&rsquo;un nourrisson de leur collectivit\u00e9 \u00e9tait attribuable \u00e0 la mauvaise qualit\u00e9 de l&rsquo;eau. Elles ont pris contact avec le CAWST et l&rsquo;organisme pour demander \u00e0 recevoir une formation sur les filtres \u00e0 eau en b\u00e9ton qu&rsquo;ils construisaient. Une fois form\u00e9es, elles ont demand\u00e9 \u00e0 emprunter le moule dans le but de fabriquer des filtres pour leurs propres maisons. Avec l&rsquo;aide du CAWST, elles ont pu amasser 2 000 $, qui leur ont permis de construire 270 filtres pour leur collectivit\u00e9. \u00ab Ces filtres sont parmi les meilleurs que nous ayons vus dans le monde. Ces femmes n&rsquo;ont pas fait d&rsquo;\u00e9tudes, mais cet exemple illustre \u00e0 quel point les femmes peuvent apporter des changements dans leur vie et leur collectivit\u00e9 lorsqu&rsquo;elles savent qu&rsquo;une solution existe. La collectivit\u00e9 commence alors \u00e0 les consid\u00e9rer comme des leaders, ce qui leur donne les moyens d&rsquo;agir \u00bb, poursuit M<sup>me<\/sup> Curry, qui a \u00e9t\u00e9 t\u00e9moin d&rsquo;exemples similaires dans le monde entier. \u00ab Passer \u00e0 l&rsquo;action donne la confiance n\u00e9cessaire pour passer \u00e0 l&rsquo;action suivante, ce qui entra\u00eene une \u00e9volution vers l&rsquo;\u00e9galit\u00e9 dans des collectivit\u00e9s traditionnellement patriarcales \u00bb, ajoute-t-elle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00e9l\u00e9brer la force int\u00e9rieure des autres et en tirer profit<b><\/b><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Le travail que nous faisons n&rsquo;est pas facile. Nous nous attaquons \u00e0 la crise mondiale de l&rsquo;eau tout en renfor\u00e7ant des capacit\u00e9s humaines. Diriger et faire cro\u00eetre un organisme dans ce secteur n&rsquo;est pas pour les \u00e2mes sensibles \u00bb, soutient M<sup>me<\/sup> Curry.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&rsquo;est pourquoi elle puise dans la force int\u00e9rieure de femmes qui suscitent des changements importants au sein de leur collectivit\u00e9, ou bien s&rsquo;inspire de celles qui c\u00e9l\u00e8brent leur propre force int\u00e9rieure. \u00ab Quand j&rsquo;ai \u00e9t\u00e9 nomm\u00e9e cheffe de la direction, j&rsquo;ai s\u00e9lectionn\u00e9 diff\u00e9rentes personnes qui sauraient, \u00e0 leur fa\u00e7on, me soutenir, m&rsquo;encadrer, me guider et me conseiller. Je me suis entour\u00e9e de gens qui m&rsquo;aideraient \u00e0 me relever. C&rsquo;est un conseil que je donnerais \u00e0 quiconque d\u00e9marre une entreprise. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M<sup>me<\/sup> Curry s&rsquo;estime aussi choy\u00e9e d&rsquo;avoir \u00e9t\u00e9 \u00e9lev\u00e9e dans un milieu o\u00f9 elle a pu d\u00e9velopper sans contraintes ses capacit\u00e9s, ses champs d&rsquo;int\u00e9r\u00eat et ses passions. \u00ab Mon p\u00e8re a \u00e9t\u00e9 un mod\u00e8le de soutien pour ma m\u00e8re et leurs trois filles \u00bb, dit-elle \u00e0 propos du r\u00f4le essentiel que jouent les alli\u00e9s dans la promotion de l&rsquo;\u00e9galit\u00e9 entre les sexes et l&rsquo;\u00e9mancipation des femmes. Elle ajoute \u00eatre consciente de son privil\u00e8ge d&rsquo;\u00eatre n\u00e9e au Canada et d&rsquo;avoir b\u00e9n\u00e9fici\u00e9 des syst\u00e8mes d&rsquo;\u00e9ducation et de sant\u00e9 que nous avons. \u00ab Du fait de ce privil\u00e8ge, nous avons la responsabilit\u00e9 de rendre service aux autres. On m&rsquo;a inculqu\u00e9 cette valeur t\u00f4t dans la vie et elle s&rsquo;est immisc\u00e9e au c\u0153ur de mes actions et de la personne que je suis devenue. On m&rsquo;a appris \u00e0 m&rsquo;appuyer sur mes champs d&rsquo;int\u00e9r\u00eat, mes passions et les services que je rends afin d&rsquo;apporter une r\u00e9elle contribution dans le monde. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&rsquo;hui, le CAWST est pr\u00eat \u00e0 \u00e9tendre ses activit\u00e9s et est en bonne voie d&rsquo;augmenter le nombre de ses clients, partenaires et collaborateurs dans chaque pays du monde en vue de toucher 100 millions de personnes d&rsquo;ici 2030. Gr\u00e2ce au soutien de toute une \u00e9quipe d&rsquo;adeptes et de femmes du monde entier qui d\u00e9couvrent leur capacit\u00e9 \u00e0 apporter des changements dans leur collectivit\u00e9, Shauna Curry est en bonne position pour mettre \u00e0 profit son sens des responsabilit\u00e9s et continuer \u00e0 faire avancer les choses.<\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse942faa40\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse942faa40\" data-dig-id=\"LP-32776-942faa40\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"Un mot de nos avocats\"><span>Un mot de nos avocats<\/span><span>Un mot de nos avocats<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse942faa40\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p class=\"wp-block-paragraph\">Le pr\u00e9sent article vise \u00e0 offrir des renseignements g\u00e9n\u00e9raux seulement et n\u2019a pas pour objet de fournir des conseils juridiques ou financiers, ni d\u2019autres conseils professionnels. Veuillez consulter un conseiller professionnel en ce qui concerne votre situation particuli\u00e8re. Les renseignements pr\u00e9sent\u00e9s sont r\u00e9put\u00e9s \u00eatre factuels et \u00e0 jour, mais nous ne garantissons pas leur exactitude et ils ne doivent pas \u00eatre consid\u00e9r\u00e9s comme une analyse exhaustive des sujets abord\u00e9s. Les opinions exprim\u00e9es refl\u00e8tent le jugement des auteurs \u00e0 la date de publication et peuvent changer. La Banque Royale du Canada et ses entit\u00e9s ne font pas la promotion, ni explicitement ni implicitement, des conseils, des avis, des renseignements, des produits ou des services de tiers.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center h5 mar-b wp-block-paragraph\"><strong>Partager cet article<\/strong><\/p>\n\n\n\n\t\t<div class=\"socials-block\">\n\t\t\t    <div class=\"social-links mob-mar-b-hlf mob-mar-t-hlf\">\n            <a class=\"social-button-wrapper sharing-custom sharing-email\" href=\"mailto:?subject=Shauna Curry s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&rsquo;action &#038;body=Bonjour, je pensais que cet article de RBC Mes finances d\u2019abord pourrait vous int\u00e9resser: https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\">\n        <img decoding=\"async\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/plugins\/rbc-blocks\/assets\/img\/icons\/icon-email.svg\"\n          alt=\"envelope icon\">\n        <span>\n          Courriel        <\/span>\n      <\/a>\n      <div class=\"social-button-wrapper sharing-copy-wrapper\">\n        <button class=\"sharing-custom sharing-copy\" data-url=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\">\n          <img decoding=\"async\"\n            src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/plugins\/rbc-blocks\/assets\/img\/icons\/icon-related.svg\"\n            alt=\"copy icon\">\n          <span id=\"sharing-copyUrl-Label\">\n            Copier l\u2019URL          <\/span>\n        <\/button>\n        <input type=\"text\" class=\"sharing-copy-text\" aria-labelledby=\"sharing-copyUrl-Label\">\n      <\/div>\n    <\/div>\n  \t\t<\/div>\n\n\t\t\n\n\t\n\t<div class=\"wp-block-tk-spacer id-4117dcd8-af43-467f-8d95-5cacae0bd4d9\" aria-hidden=\"true\"><\/div>\n\t\n\n\n\t\t\t<div class=\"wp-block-rbc-single-post-topics related-topics-links\">\n\t\t\t\t<p class=\"h5 mar-r-hlf\">Topics:<\/p>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/communaute\/\" class=\"btn topic mar-t-0 mar-r-qtr mar-b-hlf\">Communaut\u00e9<\/a>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/entreprises-dirigees-par-des-femmes\/\" class=\"btn topic mar-t-0 mar-r-qtr mar-b-hlf\">Entreprises dirig\u00e9es par des femmes<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel mob-pad-t-dbl\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<h2 class=\"wp-block-heading mar-b mob-mar-b-dbl mar-t-0\" id=\"h-a-lire-ensuite\">\u00c0 lire ensuite<\/h2>\n\n\n\t\t\t<div class=\"related-posts-type-2\">\n\t\t\t\t<div class=\"related-post-list\">\n\t\t\t\t\t<ul class=\"grid-wpr eh-wpr\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class= 'grid-one-third grid-tb-full grid-mob-full mar-b'>\n\t\t\t\t\t\t\t\t\t\t<article class=\"col-wpr mar-b-0 mar-r-0 mar-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"postcard-img-ctr post-card-image col-md-12 col-xs-6 mob-mar-b-0 pad-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/Zz0wNDJmMjgxMjZlNzcxMWYxOWI2NzRlYTdkNzQwMGRiMA.png?quality=80&amp;w=1024\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Quatre g\u00e9n\u00e9rations de propri\u00e9taires de Carman Granite\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/Zz0wNDJmMjgxMjZlNzcxMWYxOWI2NzRlYTdkNzQwMGRiMA.png 1108w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/Zz0wNDJmMjgxMjZlNzcxMWYxOWI2NzRlYTdkNzQwMGRiMA.png?resize=300,200 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/Zz0wNDJmMjgxMjZlNzcxMWYxOWI2NzRlYTdkNzQwMGRiMA.png?resize=768,512 768w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/Zz0wNDJmMjgxMjZlNzcxMWYxOWI2NzRlYTdkNzQwMGRiMA.png?resize=1024,682 1024w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card-details mob-mar-b-0 mob-mar-t-0 pad-r-0 col-md-12 col-xs-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"primary-taxonomy primary-link\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/\">\n\t\t\t\t\t\tT\u00e9moignages de r\u00e9ussite en affaires\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/lia-en-action-carman-granite\/\" class=\"card-title h4 mar-t-0\">Grav\u00e9e dans la pierre, propuls\u00e9e par l\u2019IA : une entreprise familiale centenaire tourn\u00e9e vers l\u2019avenir #IAenAction<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class= 'grid-one-third grid-tb-full grid-mob-full mar-b'>\n\t\t\t\t\t\t\t\t\t\t<article class=\"col-wpr mar-b-0 mar-r-0 mar-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"postcard-img-ctr post-card-image col-md-12 col-xs-6 mob-mar-b-0 pad-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?quality=80&amp;w=1024\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Yves et Marc Poirier Minimax Express Transport Inc.\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg 5250w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?resize=300,200 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?resize=768,512 768w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?resize=1024,683 1024w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?resize=1536,1024 1536w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/06\/IMG_2329.jpg?resize=2048,1365 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card-details mob-mar-b-0 mob-mar-t-0 pad-r-0 col-md-12 col-xs-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"primary-taxonomy primary-link\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/\">\n\t\t\t\t\t\tT\u00e9moignages de r\u00e9ussite en affaires\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/comment-minimax-express-a-transforme-sa-flotte-en-avantage-concurrentiel\/\" class=\"card-title h4 mar-t-0\">Comment Minimax Express a transform\u00e9 sa flotte en avantage concurrentiel<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class= 'grid-one-third grid-tb-full grid-mob-full mar-b'>\n\t\t\t\t\t\t\t\t\t\t<article class=\"col-wpr mar-b-0 mar-r-0 mar-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"postcard-img-ctr post-card-image col-md-12 col-xs-6 mob-mar-b-0 pad-l-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"420\" src=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png?quality=80&amp;w=1024\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\u00c9quipe d\u2019ing\u00e9nierie AM\" srcset=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png 1601w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png?resize=300,123 300w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png?resize=768,315 768w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png?resize=1024,420 1024w, https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2026\/05\/AM-Engineering-Article-Image.png?resize=1536,629 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card-details mob-mar-b-0 mob-mar-t-0 pad-r-0 col-md-12 col-xs-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"primary-taxonomy primary-link\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/\">\n\t\t\t\t\t\tT\u00e9moignages de r\u00e9ussite en affaires\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/lia-en-action-am-engineering\/\" class=\"card-title h4 mar-t-0\">De deux jours \u00e0 deux heures : Comment l\u2019IA a permis de lib\u00e9rer la croissance de la firme AM Engineering #L\u2019IA en action<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/section>\n<style class=\"advgb-styles-renderer\">\n\t\t.wp-block-tk-spacer.id-4117dcd8-af43-467f-8d95-5cacae0bd4d9 {\n\t\theight: 60px;\n\t}\n\n\t@media ( max-width: 480px ) {\n\t\t.wp-block-tk-spacer.id-4117dcd8-af43-467f-8d95-5cacae0bd4d9 {\n\t\t\theight: 30px;\n\t\t}\n\t}\t<\/style>","protected":false},"excerpt":{"rendered":"<p>Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.<\/p>\n","protected":false},"author":10,"featured_media":10761,"parent":6575,"menu_order":0,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":""},"tags":[183,196],"rbc_content_type":[121],"rbc_audience":[164],"rbc_lob_group":[122],"rbc_difficulty_level":[123],"rbc_mmm_category":[105,104,33,50,52,111],"class_list":["post-6954","rbc_my_money_matter","type-rbc_my_money_matter","status-publish","has-post-thumbnail","hentry","tag-communaute","tag-entreprises-dirigees-par-des-femmes","rbc_content_type-article","rbc_audience-proprietaires-dentreprise","rbc_lob_group-entreprises","rbc_difficulty_level-beginner","rbc_mmm_category-croissance-de-votre-entreprise","rbc_mmm_category-demarrage-dentreprise","rbc_mmm_category-entreprises","rbc_mmm_category-etapes-de-la-vie-de-lentreprise","rbc_mmm_category-inspiration","rbc_mmm_category-temoignages-de-reussite-en-affaires"],"acf":{"contently_publication_id":"349365","custom_author":"Diane Amato","rbc_video_header":"","rbc_media_duration":"","rbc_video_keywords":"","rbc_video_description":"","rbc_video_upload_date":"","rbc_toc_for_mmm_tag":"h2","rbc_toc_for_mmm_limit":6,"rbc_toc_for_mmm":null,"rbc_toc_for_mmm_action":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<meta name=\"description\" content=\"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:description\" content=\"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Banque Royale\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-23T19:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"930\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/\",\"name\":\"Shauna Curry s'attaque \u00e0 l'un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l'action - Mes finances d\u2019abord\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/09\\\/TD-2023-02-23T165153.211.jpg?quality=80\",\"datePublished\":\"2023-02-24T00:00:00+00:00\",\"dateModified\":\"2024-02-23T19:49:59+00:00\",\"description\":\"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/09\\\/TD-2023-02-23T165153.211.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/09\\\/TD-2023-02-23T165153.211.jpg?quality=80\",\"width\":930,\"height\":620,\"caption\":\"Shauna Curry\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mes finances d\u2019abord\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entreprises\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inspiration\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"T\u00e9moignages de r\u00e9ussite en affaires\",\"item\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Shauna Curry s&#8217;attaque \u00e0 l&#8217;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&#8217;action\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/#website\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/\",\"name\":\"RBC Banque Royale\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"description":"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","og_locale":"fr_FR","og_type":"article","og_description":"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.","og_url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","og_site_name":"RBC Banque Royale","article_modified_time":"2024-02-23T19:49:59+00:00","og_image":[{"width":930,"height":620,"url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","name":"Shauna Curry s'attaque \u00e0 l'un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l'action - Mes finances d\u2019abord","isPartOf":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/#primaryimage"},"image":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80","datePublished":"2023-02-24T00:00:00+00:00","dateModified":"2024-02-23T19:49:59+00:00","description":"Shauna Curry explique les changements que les femmes dot\u00e9es des moyens n\u00e9cessaires peuvent susciter dans la vie des gens et les collectivit\u00e9s.","breadcrumb":{"@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/#primaryimage","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80","contentUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80","width":930,"height":620,"caption":"Shauna Curry"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mes finances d\u2019abord","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/"},{"@type":"ListItem","position":2,"name":"Entreprises","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/"},{"@type":"ListItem","position":3,"name":"Inspiration","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/"},{"@type":"ListItem","position":4,"name":"T\u00e9moignages de r\u00e9ussite en affaires","item":"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/"},{"@type":"ListItem","position":5,"name":"Shauna Curry s&#8217;attaque \u00e0 l&#8217;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&#8217;action"}]},{"@type":"WebSite","@id":"https:\/\/www.rbcroyalbank.com\/fr-ca\/#website","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/","name":"RBC Banque Royale","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbcroyalbank.com\/fr-ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Shauna Curry s&rsquo;attaque \u00e0 l&rsquo;un des probl\u00e8mes les plus urgents au monde, et partout des femmes passent \u00e0 l&rsquo;action","url":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/entreprises\/inspiration\/temoignages-de-reussite-en-affaires\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\/"},"thumbnailUrl":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80&w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80"},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"RBC"}],"creator":["RBC"],"publisher":{"@type":"Organization","name":"RBC Banque Royale","logo":""},"keywords":["communaut\u00e9","entreprises dirig\u00e9es par des femmes"],"dateCreated":"2023-02-24T00:00:00Z","datePublished":"2023-02-24T00:00:00Z","dateModified":"2024-02-23T19:49:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Shauna Curry s&rsquo;attaque \\u00e0 l&rsquo;un des probl\\u00e8mes les plus urgents au monde, et partout des femmes passent \\u00e0 l&rsquo;action\",\"url\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/mes-finances-dabord\\\/entreprises\\\/inspiration\\\/temoignages-de-reussite-en-affaires\\\/shauna-curry-sattaque-a-lun-des-problemes-les-plus-urgents-au-monde-et-partout-des-femmes-passent-a-laction\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/09\\\/TD-2023-02-23T165153.211.jpg?quality=80&w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rbcroyalbank.com\\\/fr-ca\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/09\\\/TD-2023-02-23T165153.211.jpg?quality=80\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"RBC\"}],\"creator\":[\"RBC\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC Banque Royale\",\"logo\":\"\"},\"keywords\":[\"communaut\\u00e9\",\"entreprises dirig\\u00e9es par des femmes\"],\"dateCreated\":\"2023-02-24T00:00:00Z\",\"datePublished\":\"2023-02-24T00:00:00Z\",\"dateModified\":\"2024-02-23T19:49:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbcroyalbank.com\/p.js"},"featured_img":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-content\/uploads\/sites\/13\/2023\/09\/TD-2023-02-23T165153.211.jpg?quality=80&w=930","coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbcroyalbank.com\/fr-ca\/author\/fclaussen\/","display_name":"RBC"},"relative_dates":{"created":"Publi\u00e9 3 ans il y a","modified":"Mis \u00e0 jour 2 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 24 f\u00e9vrier 2023","modified":"Mise \u00e0 jour le 23 f\u00e9vrier 2024"},"absolute_dates_time":{"created":"Publi\u00e9 le 24 f\u00e9vrier 2023 12:00  ","modified":"Mise \u00e0 jour le 23 f\u00e9vrier 2024 7:49  "},"featured_img_caption":"","tax_additional":{"post_tag":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/communaute\/\" class=\"advgb-post-tax-term\">Communaut\u00e9<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mes-finances-dabord\/sujets\/entreprises-dirigees-par-des-femmes\/\" class=\"advgb-post-tax-term\">Entreprises dirig\u00e9es par des femmes<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Communaut\u00e9<\/span>","<span class=\"advgb-post-tax-term\">Entreprises dirig\u00e9es par des femmes<\/span>"],"slug":"post_tag","name":"\u00c9tiquettes"},"rbc_content_type":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/content-type\/article\/\" class=\"advgb-post-tax-term\">Article<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Article<\/span>"],"slug":"rbc_content_type","name":"Content Types"},"rbc_audience":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/audience\/proprietaires-d%c2%92entreprise\/\" class=\"advgb-post-tax-term\">Propri\u00e9taires d\u2019entreprise<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Propri\u00e9taires d\u2019entreprise<\/span>"],"slug":"rbc_audience","name":"Audiences"},"rbc_lob_group":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/lob-group\/entreprises\/\" class=\"advgb-post-tax-term\">Entreprises<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Entreprises<\/span>"],"slug":"rbc_lob_group","name":"LOB Groups"},"rbc_difficulty_level":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/difficulty-level\/beginner\/\" class=\"advgb-post-tax-term\">Beginner<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Beginner<\/span>"],"slug":"rbc_difficulty_level","name":"Difficulty Levels"},"rbc_mmm_category":{"linked":["<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/croissance-de-votre-entreprise\/\" class=\"advgb-post-tax-term\">Croissance de votre entreprise<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/demarrage-dentreprise\/\" class=\"advgb-post-tax-term\">D\u00e9marrage d\u2019entreprise<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/entreprises\/\" class=\"advgb-post-tax-term\">Entreprises<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/etapes-de-la-vie-de-lentreprise\/\" class=\"advgb-post-tax-term\">\u00c9tapes de la vie de l\u2019entreprise<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/inspiration\/\" class=\"advgb-post-tax-term\">Inspiration<\/a>","<a href=\"https:\/\/www.rbcroyalbank.com\/fr-ca\/mmm-category\/temoignages-de-reussite-en-affaires\/\" class=\"advgb-post-tax-term\">T\u00e9moignages de r\u00e9ussite en affaires<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Croissance de votre entreprise<\/span>","<span class=\"advgb-post-tax-term\">D\u00e9marrage d\u2019entreprise<\/span>","<span class=\"advgb-post-tax-term\">Entreprises<\/span>","<span class=\"advgb-post-tax-term\">\u00c9tapes de la vie de l\u2019entreprise<\/span>","<span class=\"advgb-post-tax-term\">Inspiration<\/span>","<span class=\"advgb-post-tax-term\">T\u00e9moignages de r\u00e9ussite en affaires<\/span>"],"slug":"rbc_mmm_category","name":"Categories"},"ep_custom_result":{"linked":[],"unlinked":[],"slug":"ep_custom_result","name":"Custom Results"}},"series_order":"","jetpack_sharing_enabled":true,"primary_tag":"183","primary_rbc_mmm_category":"111","_links":{"self":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter"}],"about":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/types\/rbc_my_money_matter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":4,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6954\/revisions"}],"predecessor-version":[{"id":27862,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6954\/revisions\/27862"}],"up":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_my_money_matter\/6575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media\/10761"}],"wp:attachment":[{"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/media?parent=6954"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/tags?post=6954"},{"taxonomy":"rbc_content_type","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_content_type?post=6954"},{"taxonomy":"rbc_audience","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_audience?post=6954"},{"taxonomy":"rbc_lob_group","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_lob_group?post=6954"},{"taxonomy":"rbc_difficulty_level","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_difficulty_level?post=6954"},{"taxonomy":"rbc_mmm_category","embeddable":true,"href":"https:\/\/www.rbcroyalbank.com\/fr-ca\/wp-json\/wp\/v2\/rbc_mmm_category?post=6954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}